{"id":29,"date":"2016-08-28T21:39:12","date_gmt":"2016-08-28T18:39:12","guid":{"rendered":"http:\/\/adnantalalini.com\/ar\/?p=29"},"modified":"2016-11-23T17:03:06","modified_gmt":"2016-11-23T14:03:06","slug":"at-sr98","status":"publish","type":"post","link":"https:\/\/adnantalalini.com\/ar\/at-sr98\/","title":{"rendered":"at-sr98"},"content":{"rendered":"<p>\u062e\u0627\u062a\u0645 \u0641\u0636\u0629 \u0639\u064a\u0627\u0631 \u0669\u0662\u0665 \u0630\u0648 \u0634\u0643\u0644 \u0641\u0646\u064a \u064a\u062a\u0648\u0633\u0637\u0647 \u062d\u062c\u0631 \u0627\u0644\u0641\u0644\u0648\u0631\u064a\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0648 \u0645\u0631\u0635\u0639 \u0628\u0627\u0644\u064a\u0627\u0642\u0648\u062a<\/p>\n<div id='gallery-1' class='gallery galleryid-29 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98a.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"233\" src=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98a-300x233.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98a-300x233.jpg 300w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98a-768x597.jpg 768w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98a.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98c.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"233\" src=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98c-300x233.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98c-300x233.jpg 300w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98c-768x597.jpg 768w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98c.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"233\" src=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98b-300x233.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98b-300x233.jpg 300w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98b-768x597.jpg 768w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98b.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98d.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"233\" src=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98d-300x233.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98d-300x233.jpg 300w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98d-768x597.jpg 768w, https:\/\/adnantalalini.com\/ar\/wp-content\/uploads\/2016\/08\/at-sr98d.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062e\u0627\u062a\u0645 \u0641\u0636\u0629 \u0639\u064a\u0627\u0631 \u0669\u0662\u0665 \u0630\u0648 \u0634\u0643\u0644 \u0641\u0646\u064a \u064a\u062a\u0648\u0633\u0637\u0647 \u062d\u062c\u0631 \u0627\u0644\u0641\u0644\u0648\u0631\u064a\u062a \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0648 \u0645\u0631\u0635\u0639 \u0628\u0627\u0644\u064a\u0627\u0642\u0648\u062a &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,42,36,5,1,14,49,15],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-precious-stones","category-fluorite","category-ruby","category-ring","category-at","category-silver","category-wholesale","category-jewellery"],"_links":{"self":[{"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":19,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"predecessor-version":[{"id":1025,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/posts\/29\/revisions\/1025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adnantalalini.com\/ar\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}